{"id":2269,"date":"2024-03-03T20:35:55","date_gmt":"2024-03-03T19:35:55","guid":{"rendered":"https:\/\/www.turbinenbau.it\/projekt\/elektrowerkgenossenschaft-welseberg-2\/"},"modified":"2025-02-06T08:06:55","modified_gmt":"2025-02-06T07:06:55","slug":"elektrowerkgenossenschaft-welseberg-2","status":"publish","type":"projekt","link":"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/","title":{"rendered":"E-Werk Graf an der Rienz"},"content":{"rendered":"","protected":false},"template":"","categories":[18],"turbinentyp":[31],"class_list":["post-2269","projekt","type-projekt","status-publish","hentry","category-turbine-construction","turbinentyp-francis-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>E-Werk Graf an der Rienz - Tschurtschenthaler Turbinenbau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E-Werk Graf an der Rienz - Tschurtschenthaler Turbinenbau\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tschurtschenthaler Turbinenbau\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T07:06:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/\",\"url\":\"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/\",\"name\":\"E-Werk Graf an der Rienz - Tschurtschenthaler Turbinenbau\",\"isPartOf\":{\"@id\":\"https:\/\/www.turbinenbau.it\/#website\"},\"datePublished\":\"2024-03-03T19:35:55+00:00\",\"dateModified\":\"2025-02-06T07:06:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.turbinenbau.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-Werk Graf an der Rienz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.turbinenbau.it\/#website\",\"url\":\"https:\/\/www.turbinenbau.it\/\",\"name\":\"Tschurtschenthaler Turbinenbau\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.turbinenbau.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E-Werk Graf an der Rienz - Tschurtschenthaler Turbinenbau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/","og_locale":"en_US","og_type":"article","og_title":"E-Werk Graf an der Rienz - Tschurtschenthaler Turbinenbau","og_url":"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/","og_site_name":"Tschurtschenthaler Turbinenbau","article_modified_time":"2025-02-06T07:06:55+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/","url":"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/","name":"E-Werk Graf an der Rienz - Tschurtschenthaler Turbinenbau","isPartOf":{"@id":"https:\/\/www.turbinenbau.it\/#website"},"datePublished":"2024-03-03T19:35:55+00:00","dateModified":"2025-02-06T07:06:55+00:00","breadcrumb":{"@id":"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.turbinenbau.it\/en\/projekt\/elektrowerkgenossenschaft-welseberg-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.turbinenbau.it\/en\/"},{"@type":"ListItem","position":2,"name":"E-Werk Graf an der Rienz"}]},{"@type":"WebSite","@id":"https:\/\/www.turbinenbau.it\/#website","url":"https:\/\/www.turbinenbau.it\/","name":"Tschurtschenthaler Turbinenbau","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.turbinenbau.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.turbinenbau.it\/en\/wp-json\/wp\/v2\/projekt\/2269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.turbinenbau.it\/en\/wp-json\/wp\/v2\/projekt"}],"about":[{"href":"https:\/\/www.turbinenbau.it\/en\/wp-json\/wp\/v2\/types\/projekt"}],"wp:attachment":[{"href":"https:\/\/www.turbinenbau.it\/en\/wp-json\/wp\/v2\/media?parent=2269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.turbinenbau.it\/en\/wp-json\/wp\/v2\/categories?post=2269"},{"taxonomy":"turbinentyp","embeddable":true,"href":"https:\/\/www.turbinenbau.it\/en\/wp-json\/wp\/v2\/turbinentyp?post=2269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}